{"id":2883,"date":"2018-07-13T16:47:48","date_gmt":"2018-07-13T16:47:48","guid":{"rendered":"http:\/\/pic-management.com\/?page_id=2883"},"modified":"2026-03-29T19:19:29","modified_gmt":"2026-03-29T17:19:29","slug":"vermittlungsservice-studenten","status":"publish","type":"page","link":"https:\/\/www.pic-management.com\/de\/studenten\/vermittlungsservice-studenten\/","title":{"rendered":"Unser Vermittlungsservice f\u00fcr Auslandspraktika"},"content":{"rendered":"<p><div class=\"et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_pb_fullwidth_section et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_fullwidth_image et_pb_fullwidth_image_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"250\" src=\"https:\/\/www.pic-management.com\/wp-content\/uploads\/2018\/05\/notre-service-stage-etudiant.jpg\" alt=\"\" title=\"\" srcset=\"https:\/\/www.pic-management.com\/wp-content\/uploads\/2018\/05\/notre-service-stage-etudiant.jpg 1200w, https:\/\/www.pic-management.com\/wp-content\/uploads\/2018\/05\/notre-service-stage-etudiant-300x63.jpg 300w, https:\/\/www.pic-management.com\/wp-content\/uploads\/2018\/05\/notre-service-stage-etudiant-768x160.jpg 768w, https:\/\/www.pic-management.com\/wp-content\/uploads\/2018\/05\/notre-service-stage-etudiant-1024x213.jpg 1024w, https:\/\/www.pic-management.com\/wp-content\/uploads\/2018\/05\/notre-service-stage-etudiant-1080x225.jpg 1080w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" class=\"wp-image-681\" \/>\n\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_justified et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Heutzutage stellt es eine gro\u00dfe Herausforderung dar, ein bezahltes Auslandspraktikum zu finden. Jedes Land hat seine eigenen Regeln und es gibt nicht viele L\u00e4nder, die Hilfestellung bei der Suche nach einem Praktikum im Ausland leisten, einschlie\u00dflich der Europ\u00e4ischen Union.<\/p>\n<p>Als Vermittlungsagentur ist es unser Ziel, die besten Bedingungen f\u00fcr diejenigen zu verhandeln, die ihr bezahltes Praktikum im Ausland finden m\u00f6chten umso eine internationale Karriere unter guten Bedingungen starten zu k\u00f6nnen.<\/p>\n<p>Unsere Hauptaufgaben sind einerseits Verhandlungen mit den Unternehmen, um bezahlte Praktika vorzuschlagen, und andererseits, um so weit wie m\u00f6glich unsere Destinationen zu diversifizieren, um unseren Studenten, die die Erfahrung im Ausland suchen, die besten M\u00f6glichkeiten zu bieten, wie zum Beispiel im Rahmen des Erasmus-Programms.<\/p>\n<p>Bei der Suche nach einem geeigneten Praktikum achten wir selbstverst\u00e4ndlich auf deine Anmerkungen und W\u00fcnsche. Zu aller erst werden wir versuchen deine Erwartungen und Motivation zu verstehen, um dir das f\u00fcr dich am besten geeignete Praktikum vorschlagen zu k\u00f6nnen. Die Idee ist dabei, dir nur Praktika vorzuschlagen, die mit deinen Vorstellungen und deinem Studienprogramm vereinbar sind. Solltest du beispielsweise ein Praktikum in einem Luxushotel suchen, werden wir unser Bestes geben etwas in diesem Bereich f\u00fcr dich zu finden.<\/p>\n<p>Wir bei PIC Management legen gro\u00dfen Wert auf eine pers\u00f6nliche Beziehung mit unseren Bewerbern w\u00e4hrend seiner Suche nach einem Praktikum. Wir sind davon \u00fcberzeugt, dass wir dir passendere Stellen vorschlagen k\u00f6nnen, wenn wir besser \u00fcber dich und deine Vorstellungen informiert sind. Gleichzeitig m\u00f6chten wir dir in jeder Phase unseres Einstellungsprozesses detaillierte Informationen zur Verf\u00fcgung stellen um eine transparente und qualitativ hochwertige Dienstleistung zu gew\u00e4hrleisten.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_2  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1  et_pb_text_align_justified et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h1>Ein unkomplizierter und effektiver Service<\/h1>\n<p>Als Vermittlungsagentur f\u00fcr Praktika ist es uns wichtig unseren Service in unseren Publikationen klar zu pr\u00e4sentieren. Wir m\u00f6chten einen agilen und effizienten Service leisten der sich wie folgt gestaltet:<\/p>\n<ul>\n<li>Nachdem wir deine Bewerbung erhalten haben, werden wir dir allgemeine Informationen \u00fcber unseren Service zuschicken und ein Skype Interview mit dir arrangieren.<\/li>\n<li>W\u00e4hrend des Interviews mit uns, stellen wir fest welche Praktikumsstellen f\u00fcr dich in Frage kommen und was deine St\u00e4rken und Schw\u00e4chen sind umso die f\u00fcr dich am besten zutreffende Stelle zu definieren.<\/li>\n<li>Danach wirst du von uns detaillierte Informationen \u00fcber unseren Service via Mail erhalten, sowie die Praktikumsstellen die wir basierend auf deinen Angaben ausfindig gemacht haben: Praktikstellen in London, bezahlte Positionen in Frankreich\u2026je nachdem wonach du suchst.<\/li>\n<li>Nachdem deine Schule oder Universit\u00e4t der Praktikumsstelle zugesagt hat, stellen wir deine Bewerbung den Unternehmen vor, f\u00fcr die du dich im Voraus entschieden hast.<\/li>\n<li>Nur wenn du die Zustimmung deine Universit\u00e4t, f\u00fcr das f\u00fcr dich interessante Praktikum erh\u00e4ltst, werden wir mit deinem Bewerbungsprozess fortfahren.<\/li>\n<li>Einzig und allein, wenn du uns mitteilst, dass dir das vorgestellte Partnerunternehmen gef\u00e4llt werden wir deine Bewerbung an das entsprechende Unternehmen weiterleiten. Falls n\u00f6tig werden wir deinen Lebenslauf \u00fcberarbeiten um ihn professioneller und deine Bewerbung so attraktiv wie m\u00f6glich zu gestalten. Dabei werden wir in keinem Falle Informationen, die in deinem Lebenslauf enthalten sind, \u00e4ndern.<\/li>\n<li>Danach arrangieren wir in Skype Interview zwischen dir und dem entsprechenden Partnerunternehmen.<\/li>\n<li>Solltest du f\u00fcr das Praktikum angenommen werden, wirst du zeitnah nach dem Bewerbungsgespr\u00e4ch mit dem Partnerunternehmen, eine Konfirmation via Mail erhalten. Zudem wirst du von uns genauere Instruktionen \u00fcber die Bezahlung unseres Vermittlungsservice erhalten. Sollte das Partnerunternehmen deine Bewerbung ablehnen, werden wir nach einem anderen Unternehmen f\u00fcr dich suchen bis wir ein geeignetes Praktikum f\u00fcr dich gefunden haben.<\/li>\n<li>Sobald wie deine Bezahlung erhalten haben, werden wir dich bei den administrativen Prozessen bis zu deinem Praktikumsstart unterst\u00fctzen, wie zum Beispiel: beim managen des Praktikumsvertrages, Informationen \u00fcber alle notwendigen Schritte, die du durchf\u00fchren musst (Visa, Versicherung etc.). Zudem werden wir dir n\u00fctzliche Informationen \u00fcber dein Praktikumsunternehmen und \u00fcber das Land, in dem du dein Praktikum machen wirst, zukommen lassen.<\/li>\n<\/ul><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_3 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_button_module_wrapper et_pb_button_0_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_0 et_hover_enabled et_pb_bg_layout_dark et_block_module\" href=\"https:\/\/www.pic-management.com\/de\/studenten\/praktikumsangebote\/\" data-icon=\"&#x3d;\">Entdecke alle unsere Praktikumsangebote im Ausland<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_4 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_3  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_3  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_2  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Unsere Vermittlungsgeb\u00fchr<\/h2>\n<div class=\"frm_forms  with_frm_style frm_style_formidable-style\" id=\"frm_form_3_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_feesf\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Geb\u00fchr<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"3\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_3\" id=\"frm_hide_fields_3\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"feesf\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_3\" name=\"frm_submit_entry_3\" value=\"7d5802b1b5\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/de\/wp-json\/wp\/v2\/pages\/2883\" \/><div id=\"frm_field_11_container\" class=\"frm_form_field  frm_html_container form-field\"><span style=\"font-family: verdana,geneva,sans-serif; font-size: 18px; color: #ff6600;\">Until 13 weeks, the fee is 385 euros. For each additional week, add 15 euros. To know the price of your program, put the duration of your internship. If you have any question, or if you require a Visa for your internship, do not hesitate to <a href=\"http:\/\/pic-management.com\/en\/contact-us\/\" target=\"_blank\">contact-us<\/a><\/span><\/div>\n<div id=\"frm_field_12_container\" class=\"frm_form_field form-field  frm_required_field frm_inline_container frm_first frm_half\">\r\n    <label for=\"field_startdatefee\" class=\"frm_primary_label\">Startdatum\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_startdatefee\" name=\"item_meta[12]\" value=\"\"  style=\"width:110px\" maxlength=\"10\" data-reqmsg=\"Startdatum can not be blank.\" aria-required=\"true\" data-invmsg=\"Invalid format.\" class=\"frm_date auto_width\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_13_container\" class=\"frm_form_field form-field  frm_required_field frm_inline_container frm_half\">\r\n    <label for=\"field_enddatefee\" class=\"frm_primary_label\">Enddatum\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_enddatefee\" name=\"item_meta[13]\" value=\"\"  style=\"width:110px\" maxlength=\"10\" data-reqmsg=\"Enddatum can not be blank.\" aria-required=\"true\" data-invmsg=\"Invalid format.\" class=\"frm_date auto_width\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_14_container\" class=\"frm_form_field form-field  frm_top_container frm_first frm_third frm_total frm_alignright\">\r\n    <label for=\"field_weeksfeed\" class=\"frm_primary_label\">Wochen\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"number\" id=\"field_weeksfeed\" name=\"item_meta[14]\" value=\"\" readonly=\"readonly\"  style=\"width:5px\" data-invmsg=\"Invalid format.\" class=\"auto_width\" aria-invalid=\"false\"   min=\"1\" max=\"9999\" step=\"any\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_15_container\" class=\"frm_form_field form-field  frm_top_container frm_third frm_total frm_alignright\">\r\n    <label for=\"field_daysfee\" class=\"frm_primary_label\">Tage\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"number\" id=\"field_daysfee\" name=\"item_meta[15]\" value=\"\" readonly=\"readonly\"  style=\"width:5px\" data-invmsg=\"Invalid format.\" class=\"auto_width\" aria-invalid=\"false\"   min=\"1\" max=\"9999\" step=\"any\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_16_container\" class=\"frm_form_field form-field  frm_top_container frm_third frm_total frm_alignright\">\r\n    <label for=\"field_monthsfee\" class=\"frm_primary_label\">Monate\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"number\" id=\"field_monthsfee\" name=\"item_meta[16]\" value=\"\" readonly=\"readonly\"  style=\"width:5px\" data-invmsg=\"Invalid format.\" class=\"auto_width\" aria-invalid=\"false\"   min=\"1\" max=\"9999\" step=\"any\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_17_container\" class=\"frm_form_field form-field  frm_top_container frm_third frm_total frm_alignright\">\r\n    <label for=\"field_monthfee\" class=\"frm_primary_label\">Monat\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"number\" id=\"field_monthfee\" name=\"item_meta[17]\" value=\"\" readonly=\"readonly\"  style=\"width:5px\" data-invmsg=\"Invalid format.\" class=\"auto_width\" aria-invalid=\"false\"   min=\"1\" max=\"9999\" step=\"any\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_18_container\" class=\"frm_form_field form-field  frm_grid_1 frm_top_container frm_total frm_grid_first frm_alignright frm_fourth\">\r\n    <label for=\"field_fee385\" class=\"frm_primary_label\">Geb\u00fchr\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"number\" id=\"field_fee385\" name=\"item_meta[18]\" value=\"\" readonly=\"readonly\"  style=\"width:100px\" data-invmsg=\"Invalid format.\" class=\"auto_width\" aria-invalid=\"false\"   min=\"0\" max=\"9999\" step=\"any\" \/>\u20ac\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_19_container\" class=\"frm_form_field form-field  frm_grid_1 frm_top_container frm_total frm_grid_first frm_alignright frm_fourth\">\r\n    <label for=\"field_fee400ormore\" class=\"frm_primary_label\">Geb\u00fchr\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"number\" id=\"field_fee400ormore\" name=\"item_meta[19]\" value=\"\" readonly=\"readonly\"  style=\"width:100px\" data-invmsg=\"Invalid format.\" class=\"auto_width\" aria-invalid=\"false\"   min=\"0\" max=\"9999\" step=\"any\" \/>\u20ac\r\n    \r\n    \r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_96_container\">\n\t\t\t<label for=\"field_icp69\" >\n\t\t\t\tFalls Du menschlich bist, lasse dieses Feld leer.\t\t\t<\/label>\n\t\t\t<input  id=\"field_icp69\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[96]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"2gynmgjUJKS8gHEBrBd1Vw8UHDuNyLl+RmDe\/CaL8Zw=\" \/><div class=\"frm_submit\">\r\n<\/div><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_tabs et_pb_tabs_0 \" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<ul class=\"et_pb_tabs_controls clearfix\">\n\t\t\t\t\t<li class=\"et_pb_tab_0 et_pb_tab_active\"><a href=\"#\">Was unsere Vermittlungsgeb\u00fchr beinhaltet<\/a><\/li><li class=\"et_pb_tab_1\"><a href=\"#\">Was unsere Vermittlungsgeb\u00fchr nicht beinhaltet<\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t<div class=\"et_pb_all_tabs\">\n\t\t\t\t\t<div class=\"et_d4_element et_pb_tab et_pb_tab_0 clearfix et_pb_active_content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_tab_content\"><ul>\n<li>Ein umfassendes Angebot an verg\u00fcteten Praktika in zahlreichen Destinationen im Ausland<\/li>\n<li>Ein mehrsprachiges Team: Spanisch, Englisch, Franz\u00f6sisch<\/li>\n<li>\u00dcberarbeitung und Verbesserung deines Lebenslaufes, falls notwendig<\/li>\n<li>Ratschl\u00e4ge und praktische Informationen f\u00fcr deine Bewerbungen, sowie Informationen \u00fcber dein Traumland f\u00fcr dein Praktikum<\/li>\n<li>Organisieren und Vorbereiten von Bewerbungsgespr\u00e4chen mit unseren Partnerunternehmen<\/li>\n<li>Eine gro\u00dfe Auswahl an bezahlten Praktikumsstellen und Destinationen<\/li>\n<li>Pers\u00f6nliche Ratschl\u00e4ge und Tipps in jeder Stufe des Bewerbungsprozesses<\/li>\n<li>Vorschlag von anderen Angeboten bis wir das richtige Praktikum f\u00fcr dich gefunden haben<\/li>\n<li>M\u00f6glichkeit, eine personalisierte Suche durchzuf\u00fchren (und neue Unternehmen zu kontaktieren), falls keine unserer Stellen auf deine Kriterien zutrifft<\/li>\n<li>Administratives Management: Einverst\u00e4ndniserkl\u00e4rung deiner Universit\u00e4t, Erasmus Papiere, Informationen \u00fcber unsere Destinationen, Tipps wie du deinen Aufenthalt im Ausland vorbereiten kannst und was du vorher erledigen musst<\/li>\n<li>Beratung und Begleitung w\u00e4hrend deines Praktikums: wir stellen sicher, dass dein Praktikum deinen Vorstellungen entspricht und k\u00fcmmern uns darum, dass dein Praktikum reibungslos verl\u00e4uft.<\/li>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_tab et_pb_tab_1 clearfix\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_tab_content\"><ul>\n<li>Transportkosten<\/li>\n<li>Versicherung<\/li>\n<li>Assurances<\/li>\n<li>Administrative Prozesse die sich auf dein Zielland beziehen (zum Beispiel: Visa Prozesse)<\/li>\n<li>Kosten, die w\u00e4hrend deines Aufenthaltes im Ausland anfallen<\/li>\n<\/ul><\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_5  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_4  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_4  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_3  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Die Studentenprofile, die wir suchen<\/h2><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_5  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_5  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_0  et_pb_text_align_justified  et_pb_blurb_position_top et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/www.pic-management.com\/wp-content\/uploads\/2018\/05\/business-presentation-1.png\" alt=\"\" class=\"et-waypoint et_pb_animation_off et_pb_animation_off_tablet et_pb_animation_off_phone wp-image-522\" \/><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h3 class=\"et_pb_module_header\"><span>Business Praktikum<\/span><\/h3>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p>Ich bin ein Student an einer Universit\u00e4t\/Hochschule, in meinem dritten Studienjahr oder starte gerade meinen Master, und habe bereits eine erste professionelle Arbeitserfahrung und bin an Business interessiert.<\/p>\n<p>Ich bin verf\u00fcgbar f\u00fcr 3 bis 6 Monate und spreche flie\u00dfend Englisch und besitze gute Kenntnisse bez\u00fcglich Microsoft Programmen und neuer Technologien.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_6  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_1  et_pb_text_align_left  et_pb_blurb_position_top et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/www.pic-management.com\/wp-content\/uploads\/2018\/05\/hotel.png\" alt=\"\" class=\"et-waypoint et_pb_animation_off et_pb_animation_off_tablet et_pb_animation_off_phone wp-image-525\" \/><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h3 class=\"et_pb_module_header\"><span>Tourismus Praktikum<\/span><\/h3>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p>Ich studiere Hotel Management, Tourismus oder Sprachen, im ersten, zweiten oder dritten Studienjahr. Zudem bin ich sehr kontaktfreudig und proaktiv.<\/p>\n<p>Weiterhin arbeite ich gerne mit Fremdsprachen und bin f\u00fcr eine Praktikumsdauer von 2 bis 6 Monaten verf\u00fcgbar.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":3432,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2883","page","type-page","status-publish","hentry"],"acf":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pic-management.com\/de\/wp-json\/wp\/v2\/pages\/2883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pic-management.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pic-management.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pic-management.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pic-management.com\/de\/wp-json\/wp\/v2\/comments?post=2883"}],"version-history":[{"count":0,"href":"https:\/\/www.pic-management.com\/de\/wp-json\/wp\/v2\/pages\/2883\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.pic-management.com\/de\/wp-json\/wp\/v2\/pages\/3432"}],"wp:attachment":[{"href":"https:\/\/www.pic-management.com\/de\/wp-json\/wp\/v2\/media?parent=2883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}